{"id":4985,"date":"2025-04-18T00:19:12","date_gmt":"2025-04-17T22:19:12","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=4985"},"modified":"2025-09-03T22:26:26","modified_gmt":"2025-09-03T20:26:26","slug":"exposition-au-parc-floral-de-paris","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/","title":{"rendered":"Exposition au Parc Floral de Paris en mai 2025"},"content":{"rendered":"<h3 class=\"wp-block-heading\">Deux toiles d&rsquo;Agnieszka Gosk-Zaleska seront pr\u00e9sent\u00e9es au Parc Floral du 1er mai au 1er juin 2025 lors de l&rsquo;exposition organis\u00e9e par le Cercle des Artistes de Paris.<\/h3>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.36920%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"4836\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/?attachment_id=4836\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-scaled.jpeg\" data-orig-size=\"1908,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1733329969&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.25&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te ouest \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te ouest \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te ouest \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 1 of 2 in full-screen\" srcset=\"https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?strip=info&#038;w=1908&#038;ssl=1 1908w\" alt=\"\u00a9 A. Gosk-Zaleska &quot; C\u00f4te ouest &quot;, 2024, acrylique en relief sur toile, 46cm x 61cm\" data-height=\"2560\" data-id=\"4836\" data-link=\"https:\/\/agoskzaleska.art\/?attachment_id=4836\" data-url=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg\" data-width=\"1908\" src=\"https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-ouest-763x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:49.63080%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" data-attachment-id=\"4835\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/?attachment_id=4835\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-scaled.jpeg\" data-orig-size=\"1880,2560\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1733329732&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;100&quot;,&quot;shutter_speed&quot;:&quot;0.2&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te est \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te est \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb C\u00f4te est \u00ab\u00a0, 2024, acrylique en relief sur toile, 46cm x 61cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg\" role=\"button\" tabindex=\"0\" aria-label=\"Open image 2 of 2 in full-screen\" srcset=\"https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?strip=info&#038;w=1880&#038;ssl=1 1880w\" alt=\"\u00a9 A. Gosk-Zaleska &quot; C\u00f4te est &quot;, 2024, acrylique en relief sur toile, 46cm x 61cm\" data-height=\"2560\" data-id=\"4835\" data-link=\"https:\/\/agoskzaleska.art\/?attachment_id=4835\" data-url=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg\" data-width=\"1880\" src=\"https:\/\/i0.wp.com\/agoskzaleska.art\/wp-content\/uploads\/2024\/12\/A-Gosk-Zaleska-Cote-est-752x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\"\/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p class=\"has-text-align-center\"><br><br> <strong>Exposition au <strong>Parc Floral de Paris <\/strong><\/strong><br> Cercle des Artistes de Paris<br><br>du 1 mai au 1 juin 2025<br><br><a href=\"https:\/\/www.parcfloraldeparis.com\/fr\">Parc Floral de Paris<\/a><br>Entr\u00e9e Nymph\u00e9as \/ Pavillon 18&nbsp;<br>Route de la Pyramide, 75012 Paris<br><br>Exposition est ouverte au public :<br>du lundi au vendredi de 14h00 \u00e0 19h00<br>le week-end et les jours f\u00e9ri\u00e9s de 10h30 \u00e0 19h00<br>le dernier jour le dimanche 1er juin fermeture \u00e0 18h00<\/p>\n\n\n\n<p class=\"has-text-align-center\"><br><\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1920\" data-attachment-id=\"5035\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/img_1089\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg\" data-orig-size=\"2560,1920\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1745668692&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;25&quot;,&quot;shutter_speed&quot;:&quot;0.00020798668885191&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Parc Floral de Paris photo : A. Gosk-Zaleska\" data-image-description=\"&lt;p&gt;Parc Floral de Paris photo : A. Gosk-Zaleska&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Parc Floral de Paris photo : A. Gosk-Zaleska&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-1024x768.jpeg\" data-id=\"5035\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg\" alt=\"Parc Floral de Paris photo : A. Gosk-Zaleska\" class=\"wp-image-5035\" srcset=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg 2560w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-300x225.jpeg 300w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-1024x768.jpeg 1024w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-768x576.jpeg 768w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-1536x1152.jpeg 1536w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-2048x1536.jpeg 2048w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-16x12.jpeg 16w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-400x300.jpeg 400w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\">Parc Floral de Paris \/ Pavillon 18 \u00a9 A. Gosk-Zaleska<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1010\" height=\"652\" data-attachment-id=\"5036\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/plan-du-parc-floral-de-paris-jpeg\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685.webp\" data-orig-size=\"1010,652\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Plan du Parc Floral de Paris\" data-image-description=\"&lt;p&gt;Plan du Parc Floral de Paris&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;Plan du Parc Floral de Paris&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685.webp\" data-id=\"5036\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685.webp\" alt=\"Plan du Parc Floral de Paris\" class=\"wp-image-5036\" srcset=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685.webp 1010w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685-300x194.webp 300w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685-768x496.webp 768w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685-18x12.webp 18w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/Plan-du-Parc-Floral-de-Paris.jpeg-e1745690109685-465x300.webp 465w\" sizes=\"auto, (max-width: 1010px) 100vw, 1010px\" \/><figcaption class=\"wp-element-caption\">Plan du Parc Floral de Paris<\/figcaption><\/figure>\n<\/figure>","protected":false},"excerpt":{"rendered":"<p><span class=\"excerpt-fade\"><\/span><\/p>","protected":false},"author":2,"featured_media":5035,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[14],"tags":[],"class_list":["post-4985","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expositions"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-17T22:19:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T20:26:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Exposition au Parc Floral de Paris en mai 2025\",\"datePublished\":\"2025-04-17T22:19:12+00:00\",\"dateModified\":\"2025-09-03T20:26:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/\"},\"wordCount\":114,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/IMG_1089-scaled.jpeg\",\"articleSection\":[\"Expositions\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/\",\"name\":\"Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/IMG_1089-scaled.jpeg\",\"datePublished\":\"2025-04-17T22:19:12+00:00\",\"dateModified\":\"2025-09-03T20:26:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/IMG_1089-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/IMG_1089-scaled.jpeg\",\"width\":2560,\"height\":1920,\"caption\":\"Parc Floral de Paris photo : A. Gosk-Zaleska\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/exposition-au-parc-floral-de-paris\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exposition au Parc Floral de Paris en mai 2025\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/","og_locale":"en_GB","og_type":"article","og_title":"Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska","og_url":"https:\/\/agoskzaleska.art\/en\/exposition-au-parc-floral-de-paris\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2025-04-17T22:19:12+00:00","article_modified_time":"2025-09-03T20:26:26+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Exposition au Parc Floral de Paris en mai 2025","datePublished":"2025-04-17T22:19:12+00:00","dateModified":"2025-09-03T20:26:26+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/"},"wordCount":114,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","articleSection":["Expositions"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/","url":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/","name":"Exposition au Parc Floral de Paris en mai 2025 - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","datePublished":"2025-04-17T22:19:12+00:00","dateModified":"2025-09-03T20:26:26+00:00","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","width":2560,"height":1920,"caption":"Parc Floral de Paris photo : A. Gosk-Zaleska"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/exposition-au-parc-floral-de-paris\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Exposition au Parc Floral de Paris en mai 2025"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2025\/04\/IMG_1089-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/4985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=4985"}],"version-history":[{"count":25,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/4985\/revisions"}],"predecessor-version":[{"id":5375,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/4985\/revisions\/5375"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/5035"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=4985"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=4985"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=4985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}