{"id":3679,"date":"2023-11-16T23:31:54","date_gmt":"2023-11-16T22:31:54","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=3679"},"modified":"2023-11-17T10:43:11","modified_gmt":"2023-11-17T09:43:11","slug":"aqua","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/aqua\/","title":{"rendered":"Aqua"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1539\" data-attachment-id=\"3684\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/aqua-3\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg\" data-orig-size=\"2560,1539\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1700216197&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;3.99&quot;,&quot;iso&quot;:&quot;80&quot;,&quot;shutter_speed&quot;:&quot;0.14285714285714&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22&amp;#215;14 cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22&amp;#215;14 cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22&amp;#215;14 cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg\" alt=\"paysage peinture eau ciel terre nature\" class=\"wp-image-3684\" srcset=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg 2560w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-300x180.jpeg 300w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><figcaption class=\"wp-element-caption\">\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22&#215;14 cm<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3684,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-3679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aqua - A. Gosk-Zaleska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/aqua\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aqua - A. Gosk-Zaleska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/aqua\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T22:31:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-17T09:43:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1539\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Aqua\",\"datePublished\":\"2023-11-16T22:31:54+00:00\",\"dateModified\":\"2023-11-17T09:43:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/\"},\"wordCount\":9,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Aqua-1-scaled.jpeg\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/\",\"name\":\"Aqua - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Aqua-1-scaled.jpeg\",\"datePublished\":\"2023-11-16T22:31:54+00:00\",\"dateModified\":\"2023-11-17T09:43:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Aqua-1-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Aqua-1-scaled.jpeg\",\"width\":2560,\"height\":1539,\"caption\":\"\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22x14 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/aqua\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aqua\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aqua - A. Gosk-Zaleska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/aqua\/","og_locale":"en_GB","og_type":"article","og_title":"Aqua - A. Gosk-Zaleska","og_url":"https:\/\/agoskzaleska.art\/en\/aqua\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2023-11-16T22:31:54+00:00","article_modified_time":"2023-11-17T09:43:11+00:00","og_image":[{"width":2560,"height":1539,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/aqua\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/aqua\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Aqua","datePublished":"2023-11-16T22:31:54+00:00","dateModified":"2023-11-17T09:43:11+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/aqua\/"},"wordCount":9,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/aqua\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/aqua\/","url":"https:\/\/agoskzaleska.art\/aqua\/","name":"Aqua - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/aqua\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/aqua\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","datePublished":"2023-11-16T22:31:54+00:00","dateModified":"2023-11-17T09:43:11+00:00","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/aqua\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/aqua\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/aqua\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","width":2560,"height":1539,"caption":"\u00a9 A. Gosk-Zaleska \u00abAqua\u00bb 2023 huile sur toile 22x14 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/aqua\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Aqua"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/11\/Aqua-1-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=3679"}],"version-history":[{"count":2,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3679\/revisions"}],"predecessor-version":[{"id":3686,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3679\/revisions\/3686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/3684"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=3679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=3679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=3679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}