{"id":3244,"date":"2023-06-29T20:11:00","date_gmt":"2023-06-29T18:11:00","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=3244"},"modified":"2024-08-22T22:40:58","modified_gmt":"2024-08-22T20:40:58","slug":"air-en-432-hz","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/","title":{"rendered":"Air en 432 Hz"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"849\" data-attachment-id=\"3239\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg\" data-orig-size=\"1069,886\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1688057684&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"A. Gosk-Zaleska \u00a0\u00bb Air en 432 Hz \u00a0\u00bb 2023, acrylique en relief sur toile 46 cm x 38 cm\" data-image-description=\"&lt;p&gt;A. Gosk-Zaleska \u00a0\u00bb Air en 432 Hz \u00a0\u00bb 2023, acrylique en relief sur toile 46 cm x 38 cm &lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;A. Gosk-Zaleska \u00a0\u00bb Air en 432 Hz \u00a0\u00bb 2023, acrylique en relief sur toile 46 cm x 38 cm &lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-1024x849.jpeg\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-1024x849.jpeg\" alt=\"Paysage, matin, lumi\u00e8re; peinture en relief sur toile\" class=\"wp-image-3239\" srcset=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-1024x849.jpeg 1024w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-300x249.jpeg 300w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-768x637.jpeg 768w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz-362x300.jpeg 362w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg 1069w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">A. Gosk-Zaleska \u00a0\u00bb Air en 432 Hz \u00a0\u00bb 2023, mixte en relief sur toile 46 cm x 38 cm<br><br><em>Collection particuli\u00e8re <\/em><\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":3239,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-3244","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Air en 432 Hz - A. Gosk-Zaleska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Air en 432 Hz - A. Gosk-Zaleska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-29T18:11:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-22T20:40:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1069\" \/>\n\t<meta property=\"og:image:height\" content=\"886\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Air en 432 Hz\",\"datePublished\":\"2023-06-29T18:11:00+00:00\",\"dateModified\":\"2024-08-22T20:40:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/\"},\"wordCount\":19,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/AIR-en-432-Hz.jpeg\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/\",\"name\":\"Air en 432 Hz - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/AIR-en-432-Hz.jpeg\",\"datePublished\":\"2023-06-29T18:11:00+00:00\",\"dateModified\":\"2024-08-22T20:40:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/AIR-en-432-Hz.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/AIR-en-432-Hz.jpeg\",\"width\":1069,\"height\":886,\"caption\":\"A. Gosk-Zaleska \\\" Air en 432 Hz \\\" 2023, acrylique en relief sur toile 46 cm x 38 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/air-en-432-hz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Air en 432 Hz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Air en 432 Hz - A. Gosk-Zaleska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/","og_locale":"en_GB","og_type":"article","og_title":"Air en 432 Hz - A. Gosk-Zaleska","og_url":"https:\/\/agoskzaleska.art\/en\/air-en-432-hz\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2023-06-29T18:11:00+00:00","article_modified_time":"2024-08-22T20:40:58+00:00","og_image":[{"width":1069,"height":886,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Air en 432 Hz","datePublished":"2023-06-29T18:11:00+00:00","dateModified":"2024-08-22T20:40:58+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/"},"wordCount":19,"commentCount":0,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/","url":"https:\/\/agoskzaleska.art\/air-en-432-hz\/","name":"Air en 432 Hz - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","datePublished":"2023-06-29T18:11:00+00:00","dateModified":"2024-08-22T20:40:58+00:00","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/air-en-432-hz\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","width":1069,"height":886,"caption":"A. Gosk-Zaleska \" Air en 432 Hz \" 2023, acrylique en relief sur toile 46 cm x 38 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/air-en-432-hz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Air en 432 Hz"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/06\/AIR-en-432-Hz.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3244","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=3244"}],"version-history":[{"count":3,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3244\/revisions"}],"predecessor-version":[{"id":4288,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3244\/revisions\/4288"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/3239"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=3244"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=3244"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=3244"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}