{"id":3020,"date":"2023-04-30T17:02:00","date_gmt":"2023-04-30T15:02:00","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=3020"},"modified":"2024-02-28T18:13:14","modified_gmt":"2024-02-28T17:13:14","slug":"labondance-de-la-lumiere","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/labondance-de-la-lumiere\/","title":{"rendered":"L&rsquo;abondance de la Lumi\u00e8re"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1001\" height=\"841\" data-attachment-id=\"3014\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/l-abondance-de-la-lumiere\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png\" data-orig-size=\"1001,841\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"A. Gosk-Zaleska \u00ab L&amp;rsquo;abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm\" data-image-description=\"&lt;p&gt;A. Gosk-Zaleska \u00ab L&amp;rsquo;abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;A. Gosk-Zaleska \u00ab L&amp;rsquo;abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png\" alt=\"paysage marin terre ciel soleil roses lumineuses\" class=\"wp-image-3014\" srcset=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png 1001w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere--300x252.png 300w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere--768x645.png 768w, https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere--357x300.png 357w\" sizes=\"auto, (max-width: 1001px) 100vw, 1001px\" \/><figcaption class=\"wp-element-caption\">A. Gosk-Zaleska \u00ab L&rsquo;abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm<br><em>Collection Particuli\u00e8re <\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"has-text-align-center\">Voici un bouquet de roses illumin\u00e9 sur l&rsquo;horizon de cette pi\u00e8ce de th\u00e9\u00e2tre quotidienne qui recommence chaque jour \u00e0 nouveau. <\/p>\n<cite>Agnieszka Gosk-Zaleska<\/cite><\/blockquote>\n\n\n\n<p> <\/p>","protected":false},"excerpt":{"rendered":"<p><span class=\"excerpt-fade\"><\/span><\/p>","protected":false},"author":2,"featured_media":3014,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-3020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;abondance de la Lumi\u00e8re - A. Gosk-Zaleska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/labondance-de-la-lumiere\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;abondance de la Lumi\u00e8re - A. Gosk-Zaleska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/labondance-de-la-lumiere\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-30T15:02:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-28T17:13:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1001\" \/>\n\t<meta property=\"og:image:height\" content=\"841\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"L&rsquo;abondance de la Lumi\u00e8re\",\"datePublished\":\"2023-04-30T15:02:00+00:00\",\"dateModified\":\"2024-02-28T17:13:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/\"},\"wordCount\":46,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/L-abondance-de-la-lumiere-.png\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/\",\"name\":\"L'abondance de la Lumi\u00e8re - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/L-abondance-de-la-lumiere-.png\",\"datePublished\":\"2023-04-30T15:02:00+00:00\",\"dateModified\":\"2024-02-28T17:13:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/L-abondance-de-la-lumiere-.png\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/L-abondance-de-la-lumiere-.png\",\"width\":1001,\"height\":841,\"caption\":\"A. Gosk-Zaleska \u00ab L'abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/labondance-de-la-lumiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;abondance de la Lumi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'abondance de la Lumi\u00e8re - A. Gosk-Zaleska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/labondance-de-la-lumiere\/","og_locale":"en_GB","og_type":"article","og_title":"L'abondance de la Lumi\u00e8re - A. Gosk-Zaleska","og_url":"https:\/\/agoskzaleska.art\/en\/labondance-de-la-lumiere\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2023-04-30T15:02:00+00:00","article_modified_time":"2024-02-28T17:13:14+00:00","og_image":[{"width":1001,"height":841,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","type":"image\/png"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"L&rsquo;abondance de la Lumi\u00e8re","datePublished":"2023-04-30T15:02:00+00:00","dateModified":"2024-02-28T17:13:14+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/"},"wordCount":46,"commentCount":0,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/","url":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/","name":"L'abondance de la Lumi\u00e8re - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","datePublished":"2023-04-30T15:02:00+00:00","dateModified":"2024-02-28T17:13:14+00:00","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","width":1001,"height":841,"caption":"A. Gosk-Zaleska \u00ab L'abondance de la Lumi\u00e8re \u00bb 2023 acrylique sur toile 46 x 38 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/labondance-de-la-lumiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;abondance de la Lumi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2023\/04\/L-abondance-de-la-lumiere-.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=3020"}],"version-history":[{"count":6,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3020\/revisions"}],"predecessor-version":[{"id":3976,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/3020\/revisions\/3976"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/3014"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=3020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=3020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=3020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}