{"id":1403,"date":"2022-09-17T19:18:25","date_gmt":"2022-09-17T17:18:25","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=1403"},"modified":"2023-09-05T15:18:45","modified_gmt":"2023-09-05T13:18:45","slug":"le-refuge","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/le-refuge\/","title":{"rendered":"Le refuge"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" data-attachment-id=\"1122\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/oeuvres\/le-refuge\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg\" data-orig-size=\"2560,2189\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\u00a9 A. Gosk-Zaleska \u00ab Le refuge \u00bb, 2022, acrylique sur bois,  48 x 40 cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska&lt;br \/&gt;\u00ab Le refuge \u00bb, 2022,&lt;br \/&gt;acrylique sur bois,&lt;br \/&gt;48 x 40 cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska&lt;br \/&gt;\u00ab Le refuge \u00bb, 2022,&lt;br \/&gt;acrylique sur bois,&lt;br \/&gt;48 x 40 cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled-1024x876.jpeg\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-1024x875.jpeg\" alt=\"paysage acrylique ciel lumi\u00e8re refuge\" class=\"wp-image-1122\"\/><figcaption class=\"wp-element-caption\">\u00a9 A. Gosk-Zaleska \u00ab Le refuge \u00bb, 2022, acrylique sur bois,  48 x 40 cm<br><em>Collection Particuli\u00e8re <\/em><\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-1403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le refuge - A. Gosk-Zaleska<\/title>\n<meta name=\"description\" content=\"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/le-refuge\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le refuge - A. Gosk-Zaleska\" \/>\n<meta property=\"og:description\" content=\"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/le-refuge\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-17T17:18:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-05T13:18:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2189\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Le refuge\",\"datePublished\":\"2022-09-17T17:18:25+00:00\",\"dateModified\":\"2023-09-05T13:18:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/\"},\"wordCount\":14,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-refuge-scaled.jpeg\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/\",\"name\":\"Le refuge - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-refuge-scaled.jpeg\",\"datePublished\":\"2022-09-17T17:18:25+00:00\",\"dateModified\":\"2023-09-05T13:18:45+00:00\",\"description\":\"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-refuge-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Le-refuge-scaled.jpeg\",\"width\":2560,\"height\":2189,\"caption\":\"\u00a9 A. Gosk-Zaleska \u00ab Le refuge \u00bb, 2022, acrylique sur bois, 48 x 40 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/le-refuge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le refuge\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le refuge - A. Gosk-Zaleska","description":"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/le-refuge\/","og_locale":"en_GB","og_type":"article","og_title":"Le refuge - A. Gosk-Zaleska","og_description":"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,","og_url":"https:\/\/agoskzaleska.art\/en\/le-refuge\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2022-09-17T17:18:25+00:00","article_modified_time":"2023-09-05T13:18:45+00:00","og_image":[{"width":2560,"height":2189,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Le refuge","datePublished":"2022-09-17T17:18:25+00:00","dateModified":"2023-09-05T13:18:45+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/"},"wordCount":14,"commentCount":0,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/","url":"https:\/\/agoskzaleska.art\/en\/le-refuge\/","name":"Le refuge - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","datePublished":"2022-09-17T17:18:25+00:00","dateModified":"2023-09-05T13:18:45+00:00","description":"\u00ab Le refuge \u00bb, 2022, acrylique sur bois,","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/en\/le-refuge\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","width":2560,"height":2189,"caption":"\u00a9 A. Gosk-Zaleska \u00ab Le refuge \u00bb, 2022, acrylique sur bois, 48 x 40 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/en\/le-refuge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Le refuge"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/07\/Le-refuge-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=1403"}],"version-history":[{"count":2,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1403\/revisions"}],"predecessor-version":[{"id":3345,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1403\/revisions\/3345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/1122"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=1403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=1403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=1403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}