{"id":1399,"date":"2022-09-17T19:10:51","date_gmt":"2022-09-17T17:10:51","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=1399"},"modified":"2025-01-15T10:33:18","modified_gmt":"2025-01-15T09:33:18","slug":"ressource","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/ressource\/","title":{"rendered":"Ressource"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" data-attachment-id=\"789\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/oeuvres\/img_5905\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg\" data-orig-size=\"2560,1806\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"\u00a9 A. Gosk-Zaleska \u00a0\u00bb Ressource \u00ab\u00a0, 2022, acrylique sur toile, 120x80cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb Ressource \u00ab\u00a0, 2022, acrylique sur toile, 120x80cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb Ressource \u00ab\u00a0, 2022, acrylique sur toile, 120x80cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled-1024x722.jpeg\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-1024x723.jpeg\" alt=\"\u0153uvre d'art acrylique peinture sur toile lumi\u00e8re\" class=\"wp-image-789\"\/><figcaption class=\"wp-element-caption\">\u00a9 A. Gosk-Zaleska \u00ab\u00a0Ressource\u00a0\u00bb, 2022, acrylique sur toile, 120x80cm<br><br><em>Collection particuli\u00e8re. <\/em><\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-1399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ressource - A. Gosk-Zaleska<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/ressource\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ressource - A. Gosk-Zaleska\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/ressource\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-17T17:10:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-15T09:33:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1806\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Ressource\",\"datePublished\":\"2022-09-17T17:10:51+00:00\",\"dateModified\":\"2025-01-15T09:33:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/\"},\"wordCount\":12,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_5905-scaled.jpeg\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/\",\"name\":\"Ressource - A. Gosk-Zaleska\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_5905-scaled.jpeg\",\"datePublished\":\"2022-09-17T17:10:51+00:00\",\"dateModified\":\"2025-01-15T09:33:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_5905-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/IMG_5905-scaled.jpeg\",\"width\":2560,\"height\":1806,\"caption\":\"\u00a9 A. Gosk-Zaleska \\\" Ressource \\\", 2022, acrylique sur toile, 120x80cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/ressource\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ressource\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ressource - A. Gosk-Zaleska","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/ressource\/","og_locale":"en_GB","og_type":"article","og_title":"Ressource - A. Gosk-Zaleska","og_url":"https:\/\/agoskzaleska.art\/en\/ressource\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2022-09-17T17:10:51+00:00","article_modified_time":"2025-01-15T09:33:18+00:00","og_image":[{"width":2560,"height":1806,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/ressource\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/ressource\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Ressource","datePublished":"2022-09-17T17:10:51+00:00","dateModified":"2025-01-15T09:33:18+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/ressource\/"},"wordCount":12,"commentCount":0,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/ressource\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/ressource\/","url":"https:\/\/agoskzaleska.art\/ressource\/","name":"Ressource - A. Gosk-Zaleska","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/ressource\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/ressource\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","datePublished":"2022-09-17T17:10:51+00:00","dateModified":"2025-01-15T09:33:18+00:00","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/ressource\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/ressource\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/ressource\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","width":2560,"height":1806,"caption":"\u00a9 A. Gosk-Zaleska \" Ressource \", 2022, acrylique sur toile, 120x80cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/ressource\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Ressource"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/05\/IMG_5905-scaled.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=1399"}],"version-history":[{"count":3,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1399\/revisions"}],"predecessor-version":[{"id":4904,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1399\/revisions\/4904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/789"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=1399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=1399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=1399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}