{"id":1237,"date":"2022-09-17T14:33:20","date_gmt":"2022-09-17T12:33:20","guid":{"rendered":"https:\/\/agoskzaleska.art\/?p=1237"},"modified":"2022-09-21T16:58:58","modified_gmt":"2022-09-21T14:58:58","slug":"entree","status":"publish","type":"post","link":"https:\/\/agoskzaleska.art\/en\/entree\/","title":{"rendered":"Entr\u00e9e"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img decoding=\"async\" data-attachment-id=\"431\" data-permalink=\"https:\/\/agoskzaleska.art\/en\/1-entree-a-gosk-zaleska-2021-mixte-sur-toile-55-x-46-cm\/\" data-orig-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\" data-orig-size=\"2560,2125\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"@ A. Gosk-Zaleska,  1. \u00a0\u00bb Entr\u00e9e \u00ab\u00a0, 2021, mixte sur toile, 55 x 46 cm\" data-image-description=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb Entr\u00e9e \u00ab\u00a0, 2021, mixte sur toile, 55 x 46 cm&lt;\/p&gt;\" data-image-caption=\"&lt;p&gt;\u00a9 A. Gosk-Zaleska \u00a0\u00bb Entr\u00e9e \u00a0\u00bb , 2021, mixte sur toile, 55 x 46 cm&lt;\/p&gt;\" data-large-file=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled-1024x850.jpg\" src=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-1024x850.jpg\" alt=\"\u0153uvre d'art paysage imaginaire mixte textur\u00e9 sur toile\" class=\"wp-image-431\"\/><figcaption>\u00a9 A. Gosk-Zaleska \u00a0\u00bb Entr\u00e9e \u00a0\u00bb 2021, mixte sur toile, 55 x 46 cm<\/figcaption><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":431,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,19],"tags":[],"class_list":["post-1237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-peintures","category-oeuvres"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entr\u00e9e<\/title>\n<meta name=\"description\" content=\"&quot; Entr\u00e9e &quot; 2021, mixte sur toile, 55 x 46 cm\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/agoskzaleska.art\/en\/entree\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entr\u00e9e\" \/>\n<meta property=\"og:description\" content=\"&quot; Entr\u00e9e &quot; 2021, mixte sur toile, 55 x 46 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/agoskzaleska.art\/en\/entree\/\" \/>\n<meta property=\"og:site_name\" content=\"A. Gosk-Zaleska\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-17T12:33:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-21T14:58:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"A. Gosk-Zaleska\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"A. Gosk-Zaleska\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/\"},\"author\":{\"name\":\"A. Gosk-Zaleska\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"headline\":\"Entr\u00e9e\",\"datePublished\":\"2022-09-17T12:33:20+00:00\",\"dateModified\":\"2022-09-21T14:58:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/\"},\"wordCount\":11,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\",\"articleSection\":[\"Peintures\",\"\u0152uvres\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/\",\"name\":\"Entr\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\",\"datePublished\":\"2022-09-17T12:33:20+00:00\",\"dateModified\":\"2022-09-21T14:58:58+00:00\",\"description\":\"\\\" Entr\u00e9e \\\" 2021, mixte sur toile, 55 x 46 cm\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#primaryimage\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg\",\"width\":2560,\"height\":2125,\"caption\":\"\u00a9 A. Gosk-Zaleska \\\" Entr\u00e9e \\\" , 2021, mixte sur toile, 55 x 46 cm\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/en\\\/entree\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/agoskzaleska.art\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entr\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#website\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/\",\"name\":\"A. Gosk-Zaleska\",\"description\":\"Artiste peintre\",\"publisher\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/agoskzaleska.art\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/#\\\/schema\\\/person\\\/fd0f4c7cf221cbb9947d3ca7110248e8\",\"name\":\"A. Gosk-Zaleska\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"url\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\",\"width\":1998,\"height\":2560,\"caption\":\"A. Gosk-Zaleska\"},\"logo\":{\"@id\":\"https:\\\/\\\/agoskzaleska.art\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg\"},\"sameAs\":[\"https:\\\/\\\/agoskzaleska.art\",\"https:\\\/\\\/www.instagram.com\\\/agoskzaleska\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entr\u00e9e","description":"\" Entr\u00e9e \" 2021, mixte sur toile, 55 x 46 cm","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/agoskzaleska.art\/en\/entree\/","og_locale":"en_GB","og_type":"article","og_title":"Entr\u00e9e","og_description":"\" Entr\u00e9e \" 2021, mixte sur toile, 55 x 46 cm","og_url":"https:\/\/agoskzaleska.art\/en\/entree\/","og_site_name":"A. Gosk-Zaleska","article_published_time":"2022-09-17T12:33:20+00:00","article_modified_time":"2022-09-21T14:58:58+00:00","og_image":[{"width":2560,"height":2125,"url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","type":"image\/jpeg"}],"author":"A. Gosk-Zaleska","twitter_card":"summary_large_image","twitter_misc":{"Written by":"A. Gosk-Zaleska","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/agoskzaleska.art\/en\/entree\/#article","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/"},"author":{"name":"A. Gosk-Zaleska","@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"headline":"Entr\u00e9e","datePublished":"2022-09-17T12:33:20+00:00","dateModified":"2022-09-21T14:58:58+00:00","mainEntityOfPage":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/"},"wordCount":11,"commentCount":0,"publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"image":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","articleSection":["Peintures","\u0152uvres"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/agoskzaleska.art\/en\/entree\/","url":"https:\/\/agoskzaleska.art\/en\/entree\/","name":"Entr\u00e9e","isPartOf":{"@id":"https:\/\/agoskzaleska.art\/#website"},"primaryImageOfPage":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/#primaryimage"},"image":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/#primaryimage"},"thumbnailUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","datePublished":"2022-09-17T12:33:20+00:00","dateModified":"2022-09-21T14:58:58+00:00","description":"\" Entr\u00e9e \" 2021, mixte sur toile, 55 x 46 cm","breadcrumb":{"@id":"https:\/\/agoskzaleska.art\/en\/entree\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/agoskzaleska.art\/en\/entree\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/en\/entree\/#primaryimage","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","width":2560,"height":2125,"caption":"\u00a9 A. Gosk-Zaleska \" Entr\u00e9e \" , 2021, mixte sur toile, 55 x 46 cm"},{"@type":"BreadcrumbList","@id":"https:\/\/agoskzaleska.art\/en\/entree\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/agoskzaleska.art\/"},{"@type":"ListItem","position":2,"name":"Entr\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/agoskzaleska.art\/#website","url":"https:\/\/agoskzaleska.art\/","name":"A. Gosk-Zaleska","description":"Artiste peintre","publisher":{"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/agoskzaleska.art\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/agoskzaleska.art\/#\/schema\/person\/fd0f4c7cf221cbb9947d3ca7110248e8","name":"A. Gosk-Zaleska","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","contentUrl":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg","width":1998,"height":2560,"caption":"A. Gosk-Zaleska"},"logo":{"@id":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/P1024952AGNIESZKA_PORTRAIT-CRAYON-3-scaled.jpeg"},"sameAs":["https:\/\/agoskzaleska.art","https:\/\/www.instagram.com\/agoskzaleska\/"]}]}},"jetpack_featured_media_url":"https:\/\/agoskzaleska.art\/wp-content\/uploads\/2022\/04\/1.-Entree-A.-Gosk-Zaleska-2021-mixte-sur-toile-55-x-46-cm-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/comments?post=1237"}],"version-history":[{"count":1,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1237\/revisions"}],"predecessor-version":[{"id":1241,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/posts\/1237\/revisions\/1241"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media\/431"}],"wp:attachment":[{"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/media?parent=1237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/categories?post=1237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agoskzaleska.art\/en\/wp-json\/wp\/v2\/tags?post=1237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}